﻿{"id":590,"date":"2016-05-13T13:52:34","date_gmt":"2016-05-13T13:52:34","guid":{"rendered":"http:\/\/ouisellyou.com\/es\/?p=590&#038;lang=ca"},"modified":"2016-05-18T13:06:45","modified_gmt":"2016-05-18T13:06:45","slug":"cccb-rastre-dart-contemporani-en-esdeveniments","status":"publish","type":"post","link":"https:\/\/ouisellyou.com\/ca\/cccb-rastre-dart-contemporani-en-esdeveniments\/","title":{"rendered":"CCCB, RASTRE D&#8217;ART CONTEMPORANI EN ESDEVENIMENTS"},"content":{"rendered":"<style type=\"text\/css\"><\/style><p>El nostre post d\u2019avui va dedicat a un dels espais m\u00e9s moderns i funcionals que podem trobar a la ciutat de Barcelona.<\/p>\n<p>Ubicat a pocs metres de Pla\u00e7a Catalunya i les Rambles, el CCCB configura un edifici emblem\u00e0tic a nivell cultural, juntament amb altres edificis situats al seu voltant, com el MACBA i algunes universitats.<\/p>\n<p>El seu espai exterior, el Pati de les Dones, \u00a0perfecte esdeveniments, representa una icona de les virtuts que es troben a la ciutat. A la part superior del seu edifici mirall s\u2019hi poden contemplar reflectits dos elements d\u2019aquesta: l\u2019arquitectura i el mar.<\/p>\n<p>En refer\u00e8ncia a la resta de l\u2019espai, hi podem trobar sales molt focalitzades en reunions, formacions, cursos, confer\u00e8ncies, exposicions, etc.<\/p>\n<p>En general podr\u00edem dir que \u00e9s un edifici que denota modernitat i minimalisme. A m\u00e9s, \u00e9s destacat per ser un edifici molt ben localitzat i amb experi\u00e8ncia en el m\u00f3n dels esdeveniments. Els seus preus s\u00f3n competitius i els seus espais variats s\u00f3n molt adaptables a diferents formats I capacitats, aix\u00ed doncs, t\u00e9 tots els punts forts necessaris per empreses que busquen un espai singular al centre de la ciutat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nostre post d\u2019avui va dedicat a un dels espais m\u00e9s moderns i funcionals que podem trobar a la ciutat de Barcelona. Ubicat a pocs metres de Pla\u00e7a Catalunya i les Rambles, el CCCB configura un edifici emblem\u00e0tic a nivell cultural, juntament amb altres edificis situats al seu voltant, com el MACBA i algunes universitats&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[316,594,114,84,116],"tags":[],"_links":{"self":[{"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/posts\/590"}],"collection":[{"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/comments?post=590"}],"version-history":[{"count":1,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/posts\/590\/revisions"}],"predecessor-version":[{"id":591,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/posts\/590\/revisions\/591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/media\/597"}],"wp:attachment":[{"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/categories?post=590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ouisellyou.com\/ca\/wp-json\/wp\/v2\/tags?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}